{"id":5708,"date":"2019-10-30T10:49:00","date_gmt":"2019-10-30T10:49:00","guid":{"rendered":"http:\/\/lajueya.net\/?p=5708"},"modified":"2020-01-24T11:20:52","modified_gmt":"2020-01-24T11:20:52","slug":"historia-de-una-bolera","status":"publish","type":"post","link":"https:\/\/lajueya.net\/index.php\/2019\/10\/30\/historia-de-una-bolera\/","title":{"rendered":"Historia de una bolera"},"content":{"rendered":"\n<p>Mazu para arreglar el castro de la bolera, en el propio castro. Imagen: David Sol\u00eds, 2019  <\/p>\n\n\n\n<p><strong> Brendan Foncueva, Jes\u00fas Montes, David Sol\u00eds.<\/strong><\/p>\n\n\n\n<p>En la peque\u00f1a localidad de Cofi\u00f1u, en el concejo de Parres, se levanta una bolera de aquellas antiguas de pueblo, en el que tantas tardes de domingo jugaban nuestros abuelos. La bolera se encuentra en el barrio de El Moriscu y pertenece hoy a Carmen Noriega Fern\u00e1ndez. <\/p>\n\n\n\n<p>Fue propiedad de Balbina y Rita L\u00f3pez Rodr\u00edguez hasta los a\u00f1os 70, y posteriormente de El\u00edas Noriega y Mar\u00eda Consuelo Fern\u00e1ndez, hasta principios de los a\u00f1os 80, a partir de esa fecha se jugaba muy espor\u00e1dicamente y en los meses de verano cuando acud\u00edan turistas al pueblo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"175\" height=\"239\" src=\"http:\/\/lajueya.net\/wp-content\/uploads\/2019\/10\/Bolera-de-cofi\u00f1u.png\" alt=\"\" class=\"wp-image-5712\"\/><figcaption> Por la izq.: Momi, Quique, Pedrito, \u00c1ngel de Amparo y Tito. Imagen: M\u00aa Consuelo Fern\u00e1ndez, 1981.<\/figcaption><\/figure><\/div>\n\n\n\n<p> La bolera tiene una longitud de veinti\u00fan metros, y el castro, un di\u00e1metro de cuatro.<\/p>\n\n\n\n<p> Hubo unos a\u00f1os de par\u00f3n hasta que la cogieron los abuelos de David. Desde entonces se volvi\u00f3 a jugar los domingos, durante una buena t e m p o r a d a . S e j u g a b a despu\u00e9s de misa, porque la gente aficionada viv\u00eda en Oviedo o Gij\u00f3n y ven\u00edan los fines de semana. <\/p>\n\n\n\n<p>Las principales partidas eran contra F\u00edos, Villar, La Salgar y Arriondas. Y los mejores jugadores eran Prida, Momi, Pepe, Pachu y Quique.<\/p>\n\n\n\n<p> Nos cuenta Francisco L\u00f3pez Car\u00fas, (vecino de Cofi\u00f1u), que en 1956 se jug\u00f3 una partida, Villar de la Cuesta contra Cofi\u00f1u. La due\u00f1a del bar, Balbina, se puso a preparar un picoteo para despu\u00e9s de la partida. Unos instantes antes, un grupo de unas 10 personas baj\u00f3 del monte y preguntaron si ten\u00eda algo para comer, entonces Balbina tuvo que comenzar a preparar m\u00e1s pinchos, y para ello hubo de pedir ayuda a su hermano Pepe, un gran jugador, que si ayudaba a su hermana no pod\u00eda jugar contra los de Villar. Pepe llam\u00f3 a Francisco L\u00f3pez \u201cPachu\u201d para que jugara, pero P a c h u , q u e p o r a q u e l entonces ten\u00eda unos 16 o 17 a\u00f1os, sab\u00eda que si perd\u00eda ten\u00eda que pagar la apuesta que se les hab\u00eda hecho a los de Villar.<\/p>\n\n\n\n<p>Pepe se dio cuenta y le dijo \u201ctu juega por mi y si perd\u00e9is ya pago yo no te preocupes\u201d. Finalmente, Pachu acept\u00f3. Al comienzo de la partida, Sindo, al enterarse de que Pepe no jugar\u00eda y que p r o b a b l e m e n t e C o f i \u00f1 u perdiese, decide no jugar, quedando compuesto el e q u i p o , e n e l \u00fa l t i m o momento, por Pachu, Quique, Luis el de Dionisia y Pedrito. Contra todo pron\u00f3stico, el equipo de Cofi\u00f1u vence al de Villar por una amplia ventaja.<\/p>\n\n\n\n<p>Francisco nos cuenta tambi\u00e9n esta otra an\u00e9cdota:<\/p>\n\n\n\n<p> \u201cHab\u00eda un se\u00f1or que se llamaba Delf\u00edn que hab\u00eda venido de la Argentina y viv\u00eda en Cofi\u00f1u. Cuando tiraba y pasaba entre los bolos, como val\u00eda 4 puntos, esperaba a que le devolvieran esa misma bola porque dec\u00eda \u201cbola castigada 4 o nada\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mazu para arreglar el castro de la bolera, en el propio castro. Imagen: David Sol\u00eds, 2019 Brendan Foncueva, Jes\u00fas Montes, David Sol\u00eds. En la peque\u00f1a localidad de Cofi\u00f1u, en el concejo de Parres, se levanta una bolera de aquellas antiguas de pueblo, en el que tantas tardes de domingo jugaban nuestros abuelos. La bolera se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5715,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25,28,18],"tags":[],"class_list":["post-5708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-lugares","category-rural"],"_links":{"self":[{"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/posts\/5708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/comments?post=5708"}],"version-history":[{"count":8,"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/posts\/5708\/revisions"}],"predecessor-version":[{"id":5737,"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/posts\/5708\/revisions\/5737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/media\/5715"}],"wp:attachment":[{"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/media?parent=5708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/categories?post=5708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lajueya.net\/index.php\/wp-json\/wp\/v2\/tags?post=5708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}